{"id":9042,"date":"2021-08-04T12:01:46","date_gmt":"2021-08-04T10:01:46","guid":{"rendered":"https:\/\/www.buecherserien.de\/de\/?p=9042"},"modified":"2021-08-04T12:01:46","modified_gmt":"2021-08-04T10:01:46","slug":"ulrike-renk-die-frau-des-seidenwebers","status":"publish","type":"post","link":"https:\/\/www.buecherserien.de\/de\/ulrike-renk-die-frau-des-seidenwebers\/","title":{"rendered":"Ulrike Renk: Die Frau des Seidenwebers"},"content":{"rendered":"<div id=\"buv\">\n<p>Das Buch &#8222;Die Frau des Seidenwebers&#8220; ist ein historischer Roman von der Autorin <a title=\"B\u00fccher von Ulrike Renk\" href=\"https:\/\/www.buecherserien.de\/ulrike-renk\/\">Ulrike Renk<\/a>.<\/p>\n<ul>\n<li>Titel bestellen bei:<\/li>\n<li class=\"buv_am\"><a title=\"Amazon.de\" href=\"https:\/\/www.amazon.de\/dp\/B004TQQXWU\/ref=nosim?tag=buecherserien-21\">Amazon<\/a><\/li>\n<li class=\"buv_th\"><a title=\"Thalia.de\" href=\"https:\/\/www.awin1.com\/cread.php?awinmid=14158&amp;awinaffid=644643&amp;ued=https%3A%2F%2Fwww.thalia.de%2Fshop%2Fhome%2Fartikeldetails%2FEAN9783841200655\">Thalia<\/a><\/li>\n<li class=\"buv_hu\"><a title=\"Hugendubel.de\" href=\"https:\/\/clk.tradedoubler.com\/click?p=249407&#038;a=3222251&#038;url=https%3A%2F%2Fwww.hugendubel.de%2Fde%2Fproduct%3Fid%3D9783841200655\">Hugendubel<\/a><\/li>\n<li class=\"buv_eb\"><a title=\"eBook.de\" href=\"https:\/\/clk.tradedoubler.com\/click?p=324630&#038;a=3222251&#038;url=https%3A%2F%2Fwww.ebook.de%2Fde%2Fproduct%3Fid%3D9783841200655\">eBook.de<\/a><\/li>\n<\/ul>\n<ol>\n<li><strong>Infos \u00fcber das Buch:<\/strong><\/li>\n<li><strong>Serie:<\/strong> Keine<\/li>\n<li><strong>Verlag:<\/strong>\u200e Aufbau<\/li>\n<li><strong>Seiten:<\/strong> 443<\/li>\n<li><strong>Ver\u00f6ffentlichung:<\/strong> 1.10.2007<\/li>\n<li><strong>Formate:<\/strong> Buch, eBook<\/li>\n<li><strong>Buch-ISBN:<\/strong>\u200e\u200e 9783746633800<\/li>\n<\/ol>\n<div class=\"clearfix\"><\/div>\n<div class=\"buech-content-tipps\" id=\"buech-1852936167\"><p>Oder gebraucht suchen bei <a href=\"https:\/\/www.awin1.com\/awclick.php?gid=362166&mid=11364&awinaffid=644643&linkid=2376078&clickref=\">Medimops<\/a>.<\/p><\/div><h2>Inhaltsangabe von &#8222;Die Frau des Seidenwebers&#8220;:<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.buecherserien.de\/de\/wp-content\/uploads\/ulrike-renk-1001.jpg\" alt=\"Die Frau des Seidenwebers von Ulrike Renk\" width=\"250\" height=\"400\" \/>Von Liebe und Seide &#8230;<br \/>\nIm Jahr 1753 reist die 25-j\u00e4hrige Mennonitin Anna von Radevormwald nach Krefeld. Sie soll ihrem Onkel den Haushalt f\u00fchren. Unterwegs lernt sie Claes kennen, der sich bei einem \u00dcberfall sch\u00fctzend vor sie stellt. Anna verliebt sich in ihn, doch f\u00fchlt er sich schon einer anderen versprochen. Die Geschichte einer Frau, die ihren eigenen Weg geht, bis sie endlich den Mann findet, der sie liebt.<br \/>\nEine opulente Familiensaga \u00fcber die Seidenweberei im 18. Jahrhundert, die auf authentischen Quellen beruht.<\/p>\n<div class=\"clearfix\"><\/div>\n<p id=\"buv_back_single\"><a href=\"https:\/\/www.buecherserien.de\/ulrike-renk\/\">Zur\u00fcck zur Autorenseite<\/a><\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Das Buch &#8222;Die Frau des Seidenwebers&#8220; ist ein historischer Roman von der Autorin Ulrike Renk. Titel bestellen bei: Amazon Thalia Hugendubel eBook.de Infos \u00fcber das Buch: Serie: Keine Verlag:\u200e Aufbau Seiten: 443 Ver\u00f6ffentlichung: 1.10.2007 Formate: Buch, eBook Buch-ISBN:\u200e\u200e 9783746633800 Inhaltsangabe von &#8222;Die Frau des Seidenwebers&#8220;: Von Liebe und Seide &#8230; Im Jahr 1753 reist die [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9043,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[20],"tags":[160],"class_list":["post-9042","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-historische-romane","tag-ulrike-renk"],"_links":{"self":[{"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/posts\/9042","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/comments?post=9042"}],"version-history":[{"count":0,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/posts\/9042\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/media\/9043"}],"wp:attachment":[{"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/media?parent=9042"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/categories?post=9042"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/tags?post=9042"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}