{"id":7600,"date":"2021-07-16T10:24:12","date_gmt":"2021-07-16T08:24:12","guid":{"rendered":"https:\/\/www.buecherserien.de\/de\/?p=7600"},"modified":"2021-07-16T10:24:12","modified_gmt":"2021-07-16T08:24:12","slug":"andreas-winkelmann-blinder-instinkt","status":"publish","type":"post","link":"https:\/\/www.buecherserien.de\/de\/andreas-winkelmann-blinder-instinkt\/","title":{"rendered":"Andreas Winkelmann: Blinder Instinkt"},"content":{"rendered":"<div id=\"buv\">\n<p>Das Buch &#8222;Blinder Instinkt&#8220; ist ein Thriller von dem Autor <a title=\"B\u00fccher von Andreas Winkelmann\" href=\"https:\/\/www.buecherserien.de\/andreas-winkelmann\/\">Andreas Winkelmann<\/a>.<\/p>\n<ul>\n<li>Titel bestellen bei:<\/li>\n<li class=\"buv_am\"><a title=\"Amazon.de\" href=\"https:\/\/www.amazon.de\/dp\/B004OVEZQQ\/ref=nosim?tag=buecherserien-21\">Amazon<\/a><\/li>\n<li class=\"buv_th\"><a title=\"Thalia.de\" href=\"https:\/\/www.awin1.com\/cread.php?awinmid=14158&amp;awinaffid=644643&amp;ued=https%3A%2F%2Fwww.thalia.de%2Fshop%2Fhome%2Fartikeldetails%2FEAN9783641041014\">Thalia<\/a><\/li>\n<li class=\"buv_hu\"><a title=\"Hugendubel.de\" href=\"https:\/\/clk.tradedoubler.com\/click?p=249407&#038;a=3222251&#038;url=https%3A%2F%2Fwww.hugendubel.de%2Fde%2Fproduct%3Fid%3D9783641041014\">Hugendubel<\/a><\/li>\n<li class=\"buv_eb\"><a title=\"eBook.de\" href=\"https:\/\/clk.tradedoubler.com\/click?p=324630&#038;a=3222251&#038;url=https%3A%2F%2Fwww.ebook.de%2Fde%2Fproduct%3Fid%3D9783641041014\">eBook.de<\/a><\/li>\n<\/ul>\n<ol>\n<li><strong>Infos \u00fcber das Buch:<\/strong><\/li>\n<li><strong>Serie:<\/strong> Keine<\/li>\n<li><strong>Verlag:<\/strong> Goldmann<\/li>\n<li><strong>Seiten:<\/strong> 416<\/li>\n<li><strong>Ver\u00f6ffentlichung:<\/strong> 18.2.2011<\/li>\n<li><strong>Formate:<\/strong> Buch, eBook, H\u00f6rbuch<\/li>\n<li><strong>Buch-ISBN:<\/strong>\u200e\u200e 9783442489428<\/li>\n<\/ol>\n<div class=\"clearfix\"><\/div>\n<div class=\"buech-content-tipps\" id=\"buech-508061348\"><p>Oder gebraucht suchen bei <a href=\"https:\/\/www.awin1.com\/awclick.php?gid=362166&mid=11364&awinaffid=644643&linkid=2376078&clickref=\">Medimops<\/a>.<\/p><\/div><h2>Inhaltsangabe von &#8222;Blinder Instinkt&#8220;:<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.buecherserien.de\/de\/wp-content\/uploads\/andreas-winkelmann-1003.jpeg\" alt=\"Blinder Instinkt von Andreas Winkelmann\" width=\"250\" height=\"400\" \/>Ein entf\u00fchrtes M\u00e4dchen, ein trauernder Bruder, ein eiskalter Psychopath&#8230;<\/p>\n<p>Ein hei\u00dfer Sommertag. In einem verwilderten Garten sitzt ein junges M\u00e4dchen auf einer Schaukel. Alles um es herum leuchtet in strahlenden Bl\u00fctenfarben, doch das M\u00e4dchen nimmt nichts davon wahr, es ist blind. Daf\u00fcr sp\u00fcrt es ganz deutlich, dass sich ihm jemand n\u00e4hert, jemand, von dem etwas zutiefst B\u00f6ses ausgeht. Es versucht noch wegzulaufen \u2013 vergeblich \u2026 Jahre sp\u00e4ter wird Kommissarin Franziska Gottlob zu einem Wohnheim f\u00fcr Kinder gerufen. Wieder ist ein junges M\u00e4dchen verschwunden. Das Kind ist blind. Und vom T\u00e4ter fehlt jede Spur.<\/p>\n<div class=\"clearfix\"><\/div>\n<p id=\"buv_back_single\"><a href=\"https:\/\/www.buecherserien.de\/andreas-winkelmann\/\">Zur\u00fcck zur Autorenseite<\/a><\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Das Buch &#8222;Blinder Instinkt&#8220; ist ein Thriller von dem Autor Andreas Winkelmann. Titel bestellen bei: Amazon Thalia Hugendubel eBook.de Infos \u00fcber das Buch: Serie: Keine Verlag: Goldmann Seiten: 416 Ver\u00f6ffentlichung: 18.2.2011 Formate: Buch, eBook, H\u00f6rbuch Buch-ISBN:\u200e\u200e 9783442489428 Inhaltsangabe von &#8222;Blinder Instinkt&#8220;: Ein entf\u00fchrtes M\u00e4dchen, ein trauernder Bruder, ein eiskalter Psychopath&#8230; Ein hei\u00dfer Sommertag. In einem [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7602,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[18],"tags":[151],"class_list":["post-7600","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-krimi-thriller","tag-andreas-winkelmann"],"_links":{"self":[{"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/posts\/7600","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/comments?post=7600"}],"version-history":[{"count":0,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/posts\/7600\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/media\/7602"}],"wp:attachment":[{"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/media?parent=7600"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/categories?post=7600"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/tags?post=7600"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}