{"id":7585,"date":"2021-07-16T09:55:25","date_gmt":"2021-07-16T07:55:25","guid":{"rendered":"https:\/\/www.buecherserien.de\/de\/?p=7585"},"modified":"2021-07-16T09:55:25","modified_gmt":"2021-07-16T07:55:25","slug":"andreas-winkelmann-der-gesang-des-blutes","status":"publish","type":"post","link":"https:\/\/www.buecherserien.de\/de\/andreas-winkelmann-der-gesang-des-blutes\/","title":{"rendered":"Andreas Winkelmann: Der Gesang des Blutes"},"content":{"rendered":"<div id=\"buv\">\n<p>Das Buch &#8222;Der Gesang des Blutes&#8220; ist ein Thriller von dem Autor <a title=\"B\u00fccher von Andreas Winkelmann\" href=\"https:\/\/www.buecherserien.de\/andreas-winkelmann\/\">Andreas Winkelmann<\/a>.<\/p>\n<ul>\n<li>Titel bestellen bei:<\/li>\n<li class=\"buv_am\"><a title=\"Amazon.de\" href=\"https:\/\/www.amazon.de\/dp\/B00EZFBXNE\/ref=nosim?tag=buecherserien-21\">Amazon<\/a><\/li>\n<li class=\"buv_th\"><a title=\"Thalia.de\" href=\"https:\/\/www.awin1.com\/cread.php?awinmid=14158&amp;awinaffid=644643&amp;ued=https%3A%2F%2Fwww.thalia.de%2Fshop%2Fhome%2Fartikeldetails%2FEAN9783644496415\">Thalia<\/a><\/li>\n<li class=\"buv_hu\"><a title=\"Hugendubel.de\" href=\"https:\/\/clk.tradedoubler.com\/click?p=249407&#038;a=3222251&#038;url=https%3A%2F%2Fwww.hugendubel.de%2Fde%2Fproduct%3Fid%3D9783644496415\">Hugendubel<\/a><\/li>\n<li class=\"buv_eb\"><a title=\"eBook.de\" href=\"https:\/\/clk.tradedoubler.com\/click?p=324630&#038;a=3222251&#038;url=https%3A%2F%2Fwww.ebook.de%2Fde%2Fproduct%3Fid%3D9783644496415\">eBook.de<\/a><\/li>\n<\/ul>\n<ol>\n<li><strong>Infos \u00fcber das Buch:<\/strong><\/li>\n<li><strong>Serie:<\/strong> Keine<\/li>\n<li><strong>Verlag:<\/strong> Rowohlt<\/li>\n<li><strong>Seiten:<\/strong> 336<\/li>\n<li><strong>Ver\u00f6ffentlichung:<\/strong> 1.10.2013<\/li>\n<li><strong>Formate:<\/strong> Buch, eBook, H\u00f6rbuch<\/li>\n<li><strong>Buch-ISBN:<\/strong>\u200e\u200e 9783499266669<\/li>\n<\/ol>\n<div class=\"clearfix\"><\/div>\n<div class=\"buech-content-tipps\" id=\"buech-468374501\"><p>Oder gebraucht suchen bei <a href=\"https:\/\/www.awin1.com\/awclick.php?gid=362166&mid=11364&awinaffid=644643&linkid=2376078&clickref=\">Medimops<\/a>.<\/p><\/div><h2>Inhaltsangabe von &#8222;Der Gesang des Blutes&#8220;:<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.buecherserien.de\/de\/wp-content\/uploads\/andreas-winkelmann-1001.jpeg\" alt=\"Der Gesang des Blutes von Andreas Winkelmann\" width=\"250\" height=\"400\" \/>Es ist im Keller. Und bald kommt es herauf.<\/p>\n<p>Die eigenen vier W\u00e4nde auf dem Land: F\u00fcr Kristin und Tom geht ein Traum in Erf\u00fcllung. Doch die junge Mutter beschleicht von Anfang an ein ungutes Gef\u00fchl. Das alte Haus ist ihr unheimlich. Als Tom kurz nach dem Einzug \u00fcberraschend stirbt, werden Kristins \u00c4ngste von Tag zu Tag schlimmer. Sie h\u00f6rt Stimmen, und nachts tr\u00e4umt sie von einer Gestalt, \u00fcber die man im Dorf spricht: von einem Scherenschleifer, der hier vor langer Zeit eine Frau get\u00f6tet haben soll. Kristin glaubt, langsam verr\u00fcckt zu werden. Die Dorfbewohner raten ihr, das neue Heim so schnell wie m\u00f6glich zu verlassen. Sie entschlie\u00dft sich zu bleiben \u2026<\/p>\n<div class=\"clearfix\"><\/div>\n<p id=\"buv_back_single\"><a href=\"https:\/\/www.buecherserien.de\/andreas-winkelmann\/\">Zur\u00fcck zur Autorenseite<\/a><\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Das Buch &#8222;Der Gesang des Blutes&#8220; ist ein Thriller von dem Autor Andreas Winkelmann. Titel bestellen bei: Amazon Thalia Hugendubel eBook.de Infos \u00fcber das Buch: Serie: Keine Verlag: Rowohlt Seiten: 336 Ver\u00f6ffentlichung: 1.10.2013 Formate: Buch, eBook, H\u00f6rbuch Buch-ISBN:\u200e\u200e 9783499266669 Inhaltsangabe von &#8222;Der Gesang des Blutes&#8220;: Es ist im Keller. Und bald kommt es herauf. Die [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7589,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[18],"tags":[151],"class_list":["post-7585","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-krimi-thriller","tag-andreas-winkelmann"],"_links":{"self":[{"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/posts\/7585","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/comments?post=7585"}],"version-history":[{"count":0,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/posts\/7585\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/media\/7589"}],"wp:attachment":[{"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/media?parent=7585"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/categories?post=7585"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/tags?post=7585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}