{"id":29738,"date":"2024-08-26T11:32:55","date_gmt":"2024-08-26T09:32:55","guid":{"rendered":"https:\/\/www.buecherserien.de\/de\/?p=29738"},"modified":"2024-08-26T11:32:55","modified_gmt":"2024-08-26T09:32:55","slug":"eva-voeller-alte-taten-neuer-zorn","status":"publish","type":"post","link":"https:\/\/www.buecherserien.de\/de\/eva-voeller-alte-taten-neuer-zorn\/","title":{"rendered":"Eva V\u00f6ller: Alte Taten, neuer Zorn"},"content":{"rendered":"<div id=\"buv\">\n<p>Der historische Kriminalroman &#8222;Alte Taten, neuer Zorn&#8220; ist der 2. Band der Carl Bruns-Reihe von der Autorin <a title=\"B\u00fccher von Eva V\u00f6ller\" href=\"https:\/\/www.buecherserien.de\/eva-voeller\/\">Eva V\u00f6ller<\/a>.<\/p>\n<ul>\n<li>Titel bestellen bei:<\/li>\n<li class=\"buv_am\"><a title=\"Amazon.de\" href=\"https:\/\/www.amazon.de\/dp\/B0CZS6N71T\/ref=nosim?tag=buecherserien-21\">Amazon<\/a><\/li>\n<li class=\"buv_th\"><a title=\"Thalia.de\" href=\"https:\/\/www.awin1.com\/cread.php?awinmid=14158&amp;awinaffid=644643&amp;ued=https%3A%2F%2Fwww.thalia.de%2Fshop%2Fhome%2Fartikeldetails%2FEAN9783426467954\">Thalia<\/a><\/li>\n<li class=\"buv_hu\"><a title=\"Hugendubel.de\" href=\"https:\/\/clk.tradedoubler.com\/click?p=249407&#038;a=3222251&#038;url=https%3A%2F%2Fwww.hugendubel.de%2Fde%2Fproduct%3Fid%3D9783426467954\">Hugendubel<\/a><\/li>\n<li class=\"buv_eb\"><a title=\"eBook.de\" href=\"https:\/\/clk.tradedoubler.com\/click?p=324630&#038;a=3222251&#038;url=https%3A%2F%2Fwww.ebook.de%2Fde%2Fproduct%3Fid%3D9783426467954\">eBook.de<\/a><\/li>\n<\/ul>\n<ol>\n<li><strong>Infos \u00fcber das Buch:<\/strong><\/li>\n<li><strong>Serie:<\/strong> Carl Bruns 2<\/li>\n<li><strong>Verlag:<\/strong> Droemer<\/li>\n<li><strong>Seiten:<\/strong> 400<\/li>\n<li><strong>Ver\u00f6ffentlichung:<\/strong> 1.9.2024<\/li>\n<li><strong>Formate:<\/strong> Buch, eBook, H\u00f6rbuch<\/li>\n<li><strong>Buch-ISBN:<\/strong>\u200e\u200e 9783426309469<\/li>\n<\/ol>\n<div class=\"clearfix\"><\/div>\n<div class=\"buech-content-tipps buech-entity-placement\" id=\"buech-4265922701\"><div id=\"buech-2325774476\"><p>Oder gebraucht suchen bei <a href=\"https:\/\/www.awin1.com\/awclick.php?gid=362166&mid=11364&awinaffid=644643&linkid=2376078&clickref=\">Medimops<\/a>.<\/p><\/div><\/div><h2>Inhaltsangabe von &#8222;Alte Taten, neuer Zorn&#8220;:<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.buecherserien.de\/de\/wp-content\/uploads\/eva-voeller-bruns-2.jpg\" alt=\"Alte Taten, neuer Zorn von Eva V\u00f6ller\" width=\"250\" height=\"400\" \/>Ein besonders heikler Fall landet 1949 auf dem Schreibtisch von Kriminalinspektor Carl Bruns: In Essen wurde der angesehene Richter Dr. Vahrendonk Opfer eines Giftmords.<\/p>\n<p>Erste Ermittlungen ergeben, dass der Tote zu Hause ein wahrer Tyrann war und seine junge Ehefrau misshandelte, als er von ihrer Aff\u00e4re erfuhr. Ist sie die gesuchte M\u00f6rderin? Pl\u00f6tzlich tauchen als Anklageschriften formulierte Vorw\u00fcrfe auf, die Vahrendonk schwer belasten: W\u00e4hrend der Nazizeit soll er aufs Grausamste seine Macht missbraucht haben. Durch die Urteile des Richters hat ein Vater seine Tochter verloren, ein Sohn seinen Vater, ein j\u00fcdischer Anwalt seine ganze Familie. Sie alle haben ein Motiv f\u00fcr den Mord. Doch f\u00fcr wen geht Vergeltung \u00fcber alles?<\/p>\n<div class=\"clearfix\"><\/div>\n<p id=\"buv_back_single\"><a href=\"https:\/\/www.buecherserien.de\/eva-voeller\/\">Zur\u00fcck zur Autorenseite<\/a><\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Der historische Kriminalroman &#8222;Alte Taten, neuer Zorn&#8220; ist der 2. Band der Carl Bruns-Reihe von der Autorin Eva V\u00f6ller. Titel bestellen bei: Amazon Thalia Hugendubel eBook.de Infos \u00fcber das Buch: Serie: Carl Bruns 2 Verlag: Droemer Seiten: 400 Ver\u00f6ffentlichung: 1.9.2024 Formate: Buch, eBook, H\u00f6rbuch Buch-ISBN:\u200e\u200e 9783426309469 Inhaltsangabe von &#8222;Alte Taten, neuer Zorn&#8220;: Ein besonders heikler [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":29739,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[18],"tags":[159],"class_list":["post-29738","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-krimi-thriller","tag-eva-voeller"],"_links":{"self":[{"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/posts\/29738","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/comments?post=29738"}],"version-history":[{"count":1,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/posts\/29738\/revisions"}],"predecessor-version":[{"id":29740,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/posts\/29738\/revisions\/29740"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/media\/29739"}],"wp:attachment":[{"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/media?parent=29738"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/categories?post=29738"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/tags?post=29738"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}