{"id":27736,"date":"2023-09-10T11:37:29","date_gmt":"2023-09-10T09:37:29","guid":{"rendered":"https:\/\/www.buecherserien.de\/de\/?p=27736"},"modified":"2023-09-10T11:37:29","modified_gmt":"2023-09-10T09:37:29","slug":"satu-raemoe-der-schatten-des-nordlichts","status":"publish","type":"post","link":"https:\/\/www.buecherserien.de\/de\/satu-raemoe-der-schatten-des-nordlichts\/","title":{"rendered":"Satu R\u00e4m\u00f6: Der Schatten des Nordlichts"},"content":{"rendered":"<div id=\"buv\">\n<p>Der Kriminalroman &#8222;Der Schatten des Nordlichts&#8220; ist der 3. Band der Hildur R\u00fanarsd\u00f3ttir-Reihe von der finnischen Autorin <a title=\"B\u00fccher von Satu R\u00e4m\u00f6\" href=\"https:\/\/www.buecherserien.de\/satu-raemoe\/\">Satu R\u00e4m\u00f6<\/a>.<\/p>\n<ul>\n<li>Titel bestellen bei:<\/li>\n<li class=\"buv_am\"><a title=\"Amazon.de\" href=\"https:\/\/www.amazon.de\/dp\/B0C1721HXC\/ref=nosim?tag=buecherserien-21\">Amazon<\/a><\/li>\n<li class=\"buv_th\"><a title=\"Thalia.de\" href=\"https:\/\/www.awin1.com\/cread.php?awinmid=14158&amp;awinaffid=644643&amp;ued=https%3A%2F%2Fwww.thalia.de%2Fshop%2Fhome%2Fartikeldetails%2FEAN9783641306335\">Thalia<\/a><\/li>\n<li class=\"buv_hu\"><a title=\"Hugendubel.de\" href=\"https:\/\/clk.tradedoubler.com\/click?p=249407&#038;a=3222251&#038;url=https%3A%2F%2Fwww.hugendubel.de%2Fde%2Fproduct%3Fid%3D9783641306335\">Hugendubel<\/a><\/li>\n<li class=\"buv_eb\"><a title=\"eBook.de\" href=\"https:\/\/clk.tradedoubler.com\/click?p=324630&#038;a=3222251&#038;url=https%3A%2F%2Fwww.ebook.de%2Fde%2Fproduct%3Fid%3D9783641306335\">eBook.de<\/a><\/li>\n<\/ul>\n<ol>\n<li><strong>Infos \u00fcber das Buch:<\/strong><\/li>\n<li><strong>Serie:<\/strong> Hildur R\u00fanarsd\u00f3ttir 3<\/li>\n<li><strong>Verlag:<\/strong> Heyne<\/li>\n<li><strong>Seiten:<\/strong> 400<\/li>\n<li><strong>Ver\u00f6ffentlichung:<\/strong> 16.10.2024<\/li>\n<li><strong>Formate:<\/strong> Buch, eBook<\/li>\n<li><strong>Buch-ISBN:<\/strong>\u200e\u200e 9783453428195<\/li>\n<\/ol>\n<div class=\"clearfix\"><\/div>\n<div class=\"buech-content-tipps\" id=\"buech-2704548513\"><p>Oder gebraucht suchen bei <a href=\"https:\/\/www.awin1.com\/awclick.php?gid=362166&mid=11364&awinaffid=644643&linkid=2376078&clickref=\">Medimops<\/a>.<\/p><\/div><h2>Inhaltsangabe von &#8222;Der Schatten des Nordlichts&#8220;:<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.buecherserien.de\/de\/wp-content\/uploads\/satu-raemoe-hildur-3.jpg\" alt=\"Der Schatten des Nordlichts von Satu R\u00e4m\u00f6\" width=\"250\" height=\"400\" \/>Am Himmel leuchten die Polarlichter, und die Bewohner der isl\u00e4ndischen Westfjorde bereiten sich auf das Weihnachtsfest vor, als ein brutaler Akt der Gewalt den kleinen Ort \u00cdsafj\u00f6r\u00f0ur ersch\u00fcttert. Ein junger Mann wurde mit einem Zaunpfahl \u00fcbel zugerichtet. Es bleibt nicht bei diesem einen Vorfall. Weitere Taten folgen, und es scheint, als ob die uralten Mythen, die man sich hier noch heute in der dunklen Jahreszeit erz\u00e4hlt, lebendiger sind denn je. Kann Kommissarin Hildur R\u00fanarsd\u00f3ttir den T\u00e4ter stoppen, bevor es zu sp\u00e4t ist?<\/p>\n<div class=\"clearfix\"><\/div>\n<p id=\"buv_back_single\"><a href=\"https:\/\/www.buecherserien.de\/satu-raemoe\/\">Zur\u00fcck zur Autorenseite<\/a><\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Der Kriminalroman &#8222;Der Schatten des Nordlichts&#8220; ist der 3. Band der Hildur R\u00fanarsd\u00f3ttir-Reihe von der finnischen Autorin Satu R\u00e4m\u00f6. Titel bestellen bei: Amazon Thalia Hugendubel eBook.de Infos \u00fcber das Buch: Serie: Hildur R\u00fanarsd\u00f3ttir 3 Verlag: Heyne Seiten: 400 Ver\u00f6ffentlichung: 16.10.2024 Formate: Buch, eBook Buch-ISBN:\u200e\u200e 9783453428195 Inhaltsangabe von &#8222;Der Schatten des Nordlichts&#8220;: Am Himmel leuchten die [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":27738,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[18],"tags":[593],"class_list":["post-27736","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-krimi-thriller","tag-satu-raemoe"],"_links":{"self":[{"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/posts\/27736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/comments?post=27736"}],"version-history":[{"count":0,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/posts\/27736\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/media\/27738"}],"wp:attachment":[{"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/media?parent=27736"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/categories?post=27736"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/tags?post=27736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}