{"id":27670,"date":"2023-08-22T09:58:09","date_gmt":"2023-08-22T07:58:09","guid":{"rendered":"https:\/\/www.buecherserien.de\/de\/?p=27670"},"modified":"2023-08-22T09:58:09","modified_gmt":"2023-08-22T07:58:09","slug":"eva-voeller-helle-tage-dunkle-schuld","status":"publish","type":"post","link":"https:\/\/www.buecherserien.de\/de\/eva-voeller-helle-tage-dunkle-schuld\/","title":{"rendered":"Eva V\u00f6ller: Helle Tage, dunkle Schuld"},"content":{"rendered":"<div id=\"buv\">\n<p>Der historische Kriminalroman &#8222;Helle Tage, dunkle Schuld&#8220; ist der 1. Band der Carl Bruns-Reihe von der Autorin <a title=\"B\u00fccher von Eva V\u00f6ller\" href=\"https:\/\/www.buecherserien.de\/eva-voeller\/\">Eva V\u00f6ller<\/a>.<\/p>\n<ul>\n<li>Titel bestellen bei:<\/li>\n<li class=\"buv_am\"><a title=\"Amazon.de\" href=\"https:\/\/www.amazon.de\/dp\/B0C263J9H8\/ref=nosim?tag=buecherserien-21\">Amazon<\/a><\/li>\n<li class=\"buv_th\"><a title=\"Thalia.de\" href=\"https:\/\/www.awin1.com\/cread.php?awinmid=14158&amp;awinaffid=644643&amp;ued=https%3A%2F%2Fwww.thalia.de%2Fshop%2Fhome%2Fartikeldetails%2FEAN9783426467947\">Thalia<\/a><\/li>\n<li class=\"buv_hu\"><a title=\"Hugendubel.de\" href=\"https:\/\/clk.tradedoubler.com\/click?p=249407&#038;a=3222251&#038;url=https%3A%2F%2Fwww.hugendubel.de%2Fde%2Fproduct%3Fid%3D9783426467947\">Hugendubel<\/a><\/li>\n<li class=\"buv_eb\"><a title=\"eBook.de\" href=\"https:\/\/clk.tradedoubler.com\/click?p=324630&#038;a=3222251&#038;url=https%3A%2F%2Fwww.ebook.de%2Fde%2Fproduct%3Fid%3D9783426467947\">eBook.de<\/a><\/li>\n<\/ul>\n<ol>\n<li><strong>Infos \u00fcber das Buch:<\/strong><\/li>\n<li><strong>Serie:<\/strong> Carl Bruns 1<\/li>\n<li><strong>Verlag:<\/strong> Droemer<\/li>\n<li><strong>Seiten:<\/strong> 400<\/li>\n<li><strong>Ver\u00f6ffentlichung:<\/strong> 1.9.2023<\/li>\n<li><strong>Formate:<\/strong> Buch, eBook, H\u00f6rbuch<\/li>\n<li><strong>Buch-ISBN:<\/strong>\u200e\u200e 9783426309445<\/li>\n<\/ol>\n<div class=\"clearfix\"><\/div>\n<div class=\"buech-content-tipps buech-entity-placement\" id=\"buech-2964947296\"><div id=\"buech-1331931734\"><p>Oder gebraucht suchen bei <a href=\"https:\/\/www.awin1.com\/awclick.php?gid=362166&mid=11364&awinaffid=644643&linkid=2376078&clickref=\">Medimops<\/a>.<\/p><\/div><\/div><h2>Inhaltsangabe von &#8222;Helle Tage, dunkle Schuld&#8220;:<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.buecherserien.de\/de\/wp-content\/uploads\/eva-voeller-bruns-1.jpg\" alt=\"Helle Tage, dunkle Schuld von Eva V\u00f6ller\" width=\"250\" height=\"400\" \/>Ruhrgebiet, 1948. Der Kriminalbeamte Carl Bruns arbeitet f\u00fcr die Abteilung Kapitalverbrechen im Essener Polizeipr\u00e4sidium, nachdem er w\u00e4hrend der Nazizeit seinen Beruf nicht aus\u00fcben konnte. Im Zuge von Mordermittlungen erf\u00e4hrt er von einer grauenvollen Bluttat, die sich drei Jahre zuvor gegen Kriegsende ereignet hat. W\u00e4hrend er dem fl\u00fcchtigen T\u00e4ter von damals nachsp\u00fcrt, geschehen weitere Morde. Erst allm\u00e4hlich erkennt Carl Bruns, dass sie Teile eines t\u00f6dlichen Puzzles sind. Nicht nur er selbst ger\u00e4t dabei ins Fadenkreuz des M\u00f6rders, sondern auch die Frau, die er liebt \u2013 die verwitwete Krankenschwester Anne, die verzweifelt an eine bessere Zukunft f\u00fcr sich und ihre Schwestern glaubt. Doch Anne h\u00fctet ein d\u00fcsteres Geheimnis, von dem auch Carl nichts ahnt \u2026<\/p>\n<div class=\"clearfix\"><\/div>\n<p id=\"buv_back_single\"><a href=\"https:\/\/www.buecherserien.de\/eva-voeller\/\">Zur\u00fcck zur Autorenseite<\/a><\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Der historische Kriminalroman &#8222;Helle Tage, dunkle Schuld&#8220; ist der 1. Band der Carl Bruns-Reihe von der Autorin Eva V\u00f6ller. Titel bestellen bei: Amazon Thalia Hugendubel eBook.de Infos \u00fcber das Buch: Serie: Carl Bruns 1 Verlag: Droemer Seiten: 400 Ver\u00f6ffentlichung: 1.9.2023 Formate: Buch, eBook, H\u00f6rbuch Buch-ISBN:\u200e\u200e 9783426309445 Inhaltsangabe von &#8222;Helle Tage, dunkle Schuld&#8220;: Ruhrgebiet, 1948. Der [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":27671,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[18],"tags":[159],"class_list":["post-27670","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-krimi-thriller","tag-eva-voeller"],"_links":{"self":[{"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/posts\/27670","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/comments?post=27670"}],"version-history":[{"count":0,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/posts\/27670\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/media\/27671"}],"wp:attachment":[{"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/media?parent=27670"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/categories?post=27670"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/tags?post=27670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}