{"id":27415,"date":"2023-07-14T12:12:59","date_gmt":"2023-07-14T10:12:59","guid":{"rendered":"https:\/\/www.buecherserien.de\/de\/?p=27415"},"modified":"2023-07-14T12:12:59","modified_gmt":"2023-07-14T10:12:59","slug":"frank-goldammer-bruch-in-eisigen-naechten","status":"publish","type":"post","link":"https:\/\/www.buecherserien.de\/de\/frank-goldammer-bruch-in-eisigen-naechten\/","title":{"rendered":"Frank Goldammer: Bruch: In eisigen N\u00e4chten"},"content":{"rendered":"<div id=\"buv\">\n<p>Der Kriminalroman &#8222;Bruch: In eisigen N\u00e4chten&#8220; ist der 2. Band der Felix Bruch-Reihe von dem deutschen Autor <a title=\"B\u00fccher von Frank Goldammer\" href=\"https:\/\/www.buecherserien.de\/frank-goldammer\/\">Frank Goldammer<\/a>.<\/p>\n<ul>\n<li>Titel bestellen bei:<\/li>\n<li class=\"buv_am\"><a title=\"Amazon.de\" href=\"https:\/\/www.amazon.de\/dp\/B0C12SBXGR\/ref=nosim?tag=buecherserien-21\">Amazon<\/a><\/li>\n<li class=\"buv_th\"><a title=\"Thalia.de\" href=\"https:\/\/www.awin1.com\/cread.php?awinmid=14158&amp;awinaffid=644643&amp;ued=https%3A%2F%2Fwww.thalia.de%2Fshop%2Fhome%2Fartikeldetails%2FEAN9783644010468\">Thalia<\/a><\/li>\n<li class=\"buv_hu\"><a title=\"Hugendubel.de\" href=\"https:\/\/clk.tradedoubler.com\/click?p=249407&#038;a=3222251&#038;url=https%3A%2F%2Fwww.hugendubel.de%2Fde%2Fproduct%3Fid%3D9783644010468\">Hugendubel<\/a><\/li>\n<li class=\"buv_eb\"><a title=\"eBook.de\" href=\"https:\/\/clk.tradedoubler.com\/click?p=324630&#038;a=3222251&#038;url=https%3A%2F%2Fwww.ebook.de%2Fde%2Fproduct%3Fid%3D9783644010468\">eBook.de<\/a><\/li>\n<\/ul>\n<ol>\n<li><strong>Infos \u00fcber das Buch:<\/strong><\/li>\n<li><strong>Serie:<\/strong> Felix Bruch 2<\/li>\n<li><strong>Verlag:<\/strong> Wunderlich<\/li>\n<li><strong>Seiten:<\/strong> 416<\/li>\n<li><strong>Ver\u00f6ffentlichung:<\/strong> 1.8.2023<\/li>\n<li><strong>Formate:<\/strong> Buch, eBook<\/li>\n<li><strong>Buch-ISBN:<\/strong> 9783805200912<\/li>\n<\/ol>\n<div class=\"clearfix\"><\/div>\n<div class=\"buech-content-tipps\" id=\"buech-2524637801\"><p>Oder gebraucht suchen bei <a href=\"https:\/\/www.awin1.com\/awclick.php?gid=362166&mid=11364&awinaffid=644643&linkid=2376078&clickref=\">Medimops<\/a>.<\/p><\/div><h2>Inhaltsangabe von &#8222;In eisigen N\u00e4chten&#8220;:<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.buecherserien.de\/de\/wp-content\/uploads\/frank-goldammer-bruch-2.jpg\" alt=\"In eisigen N\u00e4chten von Frank Goldammer\" width=\"250\" height=\"400\" \/>Nichts ist vergessen.<\/p>\n<p>Ein interner Mordfall streut Angst und Misstrauen unter den Kollegen der Dresdner Mordkommission. In dieser Hektik werden die Ermittler Felix Bruch und Nicole Schauer zu einem Tatort gerufen. Ein Mann wurde in seinem Haus angeschossen, die vermeintliche T\u00e4terin war noch vor Ort. Schauer ist geschockt, als sie erf\u00e4hrt, dass Bruch die junge Frau kennt. Als Bruch und Schauer die Ermittlungen aufnehmen wollen, wird die gesamte Abteilung beurlaubt. Doch Schauer bekommt Informationen zugespielt, die sie dazu veranlassen, auf eigene Faust weitere Nachforschungen anzustellen. Bruch wird durch die Ereignisse ruhelos, er gr\u00e4bt tief in seiner Vergangenheit und beginnt langsam die Kontrolle zu verlieren \u2026<\/p>\n<div class=\"clearfix\"><\/div>\n<p id=\"buv_back_single\"><a href=\"https:\/\/www.buecherserien.de\/frank-goldammer\/\">Zur\u00fcck zur Autorenseite<\/a><\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Der Kriminalroman &#8222;Bruch: In eisigen N\u00e4chten&#8220; ist der 2. Band der Felix Bruch-Reihe von dem deutschen Autor Frank Goldammer. Titel bestellen bei: Amazon Thalia Hugendubel eBook.de Infos \u00fcber das Buch: Serie: Felix Bruch 2 Verlag: Wunderlich Seiten: 416 Ver\u00f6ffentlichung: 1.8.2023 Formate: Buch, eBook Buch-ISBN: 9783805200912 Inhaltsangabe von &#8222;In eisigen N\u00e4chten&#8220;: Nichts ist vergessen. Ein interner [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":27416,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[18],"tags":[49],"class_list":["post-27415","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-krimi-thriller","tag-frank-goldammer"],"_links":{"self":[{"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/posts\/27415","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/comments?post=27415"}],"version-history":[{"count":0,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/posts\/27415\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/media\/27416"}],"wp:attachment":[{"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/media?parent=27415"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/categories?post=27415"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/tags?post=27415"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}