{"id":25094,"date":"2022-10-08T09:47:47","date_gmt":"2022-10-08T07:47:47","guid":{"rendered":"https:\/\/www.buecherserien.de\/de\/?p=25094"},"modified":"2022-10-08T09:47:47","modified_gmt":"2022-10-08T07:47:47","slug":"volker-kutscher-der-nasse-fisch","status":"publish","type":"post","link":"https:\/\/www.buecherserien.de\/de\/volker-kutscher-der-nasse-fisch\/","title":{"rendered":"Volker Kutscher: Der nasse Fisch"},"content":{"rendered":"<div id=\"buv\">\n<p>Der historische Kriminalroman &#8222;Der nasse Fisch&#8220; ist der 1. Band der Gereon Rath-Reihe von dem deutschen Autor <a title=\"B\u00fccher von Volker Kutscher\" href=\"https:\/\/www.buecherserien.de\/volker-kutscher\/\">Volker Kutscher<\/a>.<\/p>\n<ul>\n<li>Titel bestellen bei:<\/li>\n<li class=\"buv_am\"><a title=\"Amazon.de\" href=\"https:\/\/www.amazon.de\/dp\/B081B83HZ4\/ref=nosim?tag=buecherserien-21\">Amazon<\/a><\/li>\n<li class=\"buv_th\"><a title=\"Thalia.de\" href=\"https:\/\/www.awin1.com\/cread.php?awinmid=14158&amp;awinaffid=644643&amp;ued=https%3A%2F%2Fwww.thalia.de%2Fshop%2Fhome%2Fartikeldetails%2FEAN9783492996419\">Thalia<\/a><\/li>\n<li class=\"buv_hu\"><a title=\"Hugendubel.de\" href=\"https:\/\/clk.tradedoubler.com\/click?p=249407&#038;a=3222251&#038;url=https%3A%2F%2Fwww.hugendubel.de%2Fde%2Fproduct%3Fid%3D9783492996419\">Hugendubel<\/a><\/li>\n<li class=\"buv_eb\"><a title=\"eBook.de\" href=\"https:\/\/clk.tradedoubler.com\/click?p=324630&#038;a=3222251&#038;url=https%3A%2F%2Fwww.ebook.de%2Fde%2Fproduct%3Fid%3D9783492996419\">eBook.de<\/a><\/li>\n<\/ul>\n<ol>\n<li><strong>Infos \u00fcber das Buch:<\/strong><\/li>\n<li><strong>Serie:<\/strong> Gereon Rath 1<\/li>\n<li><strong>Verlag:<\/strong> Kiepenheuer &#038; Witsch<\/li>\n<li><strong>Seiten:<\/strong> 542<\/li>\n<li><strong>Ver\u00f6ffentlichung:<\/strong> 27.8.2007<\/li>\n<li><strong>Formate:<\/strong> Buch, eBook, H\u00f6rbuch<\/li>\n<li><strong>Buch-ISBN:<\/strong> 9783462040227<\/li>\n<\/ol>\n<div class=\"clearfix\"><\/div>\n<div class=\"buech-content-tipps\" id=\"buech-663648340\"><p>Oder gebraucht suchen bei <a href=\"https:\/\/www.awin1.com\/awclick.php?gid=362166&mid=11364&awinaffid=644643&linkid=2376078&clickref=\">Medimops<\/a>.<\/p><\/div><h2>Inhaltsangabe von &#8222;Der nasse Fisch&#8220;:<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.buecherserien.de\/de\/wp-content\/uploads\/volker-kutscher-rath-1.jpg\" alt=\"Der nasse Fisch von Volker Kutscher\" width=\"250\" height=\"400\" \/>Mit diesem Roman beginnt die spektakul\u00e4re Serie, in der Kutscher seinen Kriminalkommissar Gereon Rath in die politischen und gesellschaftlichen Umbr\u00fcche im Berlin der sp\u00e4ten 20er-Jahre f\u00fchrt.<\/p>\n<p>Rath, neu in Berlin und abgestellt bei der Sitte, erlebt eine Weltstadt im Rausch, die von sozialen und politischen Spannungen zerrissen ist. Ungefragt schaltet sich der Kommissar in die stagnierenden Ermittlungen eines Mordfalls ein \u2013 und st\u00f6\u00dft in ein Wespennest. Dann verliebt Rath sich in Charly, Stenotypistin in der Mordkommission, und missbraucht ihr Insiderwissen f\u00fcr seine einsamen Ermittlungen.<\/p>\n<div class=\"clearfix\"><\/div>\n<p id=\"buv_back_single\"><a href=\"https:\/\/www.buecherserien.de\/volker-kutscher\/\">Zur\u00fcck zur Autorenseite<\/a><\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Der historische Kriminalroman &#8222;Der nasse Fisch&#8220; ist der 1. Band der Gereon Rath-Reihe von dem deutschen Autor Volker Kutscher. Titel bestellen bei: Amazon Thalia Hugendubel eBook.de Infos \u00fcber das Buch: Serie: Gereon Rath 1 Verlag: Kiepenheuer &#038; Witsch Seiten: 542 Ver\u00f6ffentlichung: 27.8.2007 Formate: Buch, eBook, H\u00f6rbuch Buch-ISBN: 9783462040227 Inhaltsangabe von &#8222;Der nasse Fisch&#8220;: Mit diesem [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":25095,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[20,18],"tags":[414],"class_list":["post-25094","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-historische-romane","category-krimi-thriller","tag-volker-kutscher"],"_links":{"self":[{"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/posts\/25094","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/comments?post=25094"}],"version-history":[{"count":0,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/posts\/25094\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/media\/25095"}],"wp:attachment":[{"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/media?parent=25094"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/categories?post=25094"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/tags?post=25094"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}