{"id":24537,"date":"2022-09-23T11:45:39","date_gmt":"2022-09-23T09:45:39","guid":{"rendered":"https:\/\/www.buecherserien.de\/de\/?p=24537"},"modified":"2022-09-23T11:45:39","modified_gmt":"2022-09-23T09:45:39","slug":"gabriella-ullberg-westin-der-gejagte","status":"publish","type":"post","link":"https:\/\/www.buecherserien.de\/de\/gabriella-ullberg-westin-der-gejagte\/","title":{"rendered":"Gabriella Ullberg Westin: Der Gejagte"},"content":{"rendered":"<div id=\"buv\">\n<p>Der Kriminalroman &#8222;Der Gejagte&#8220; ist der 4. Band der Johan Rokka-Reihe von der schwedischen Autorin <a title=\"B\u00fccher von Gabriella Ullberg Westin\" href=\"https:\/\/www.buecherserien.de\/gabriella-ullberg-westin\/\">Gabriella Ullberg Westin<\/a>.<\/p>\n<ul>\n<li>Titel bestellen bei:<\/li>\n<li class=\"buv_am\"><a title=\"Amazon.de\" href=\"https:\/\/www.amazon.de\/dp\/B085DYPJSS\/ref=nosim?tag=buecherserien-21\">Amazon<\/a><\/li>\n<li class=\"buv_th\"><a title=\"Thalia.de\" href=\"https:\/\/www.awin1.com\/cread.php?awinmid=14158&amp;awinaffid=644643&amp;ued=https%3A%2F%2Fwww.thalia.de%2Fshop%2Fhome%2Fartikeldetails%2FEAN9783959675963\">Thalia<\/a><\/li>\n<li class=\"buv_hu\"><a title=\"Hugendubel.de\" href=\"https:\/\/clk.tradedoubler.com\/click?p=249407&#038;a=3222251&#038;url=https%3A%2F%2Fwww.hugendubel.de%2Fde%2Fproduct%3Fid%3D9783959675963\">Hugendubel<\/a><\/li>\n<li class=\"buv_eb\"><a title=\"eBook.de\" href=\"https:\/\/clk.tradedoubler.com\/click?p=324630&#038;a=3222251&#038;url=https%3A%2F%2Fwww.ebook.de%2Fde%2Fproduct%3Fid%3D9783959675963\">eBook.de<\/a><\/li>\n<\/ul>\n<ol>\n<li><strong>Infos \u00fcber das Buch:<\/strong><\/li>\n<li><strong>Serie:<\/strong> Johan Rokka 4<\/li>\n<li><strong>Verlag:<\/strong> HarperCollins<\/li>\n<li><strong>Seiten:<\/strong> 368<\/li>\n<li><strong>Ver\u00f6ffentlichung:<\/strong> 24.8.2021<\/li>\n<li><strong>Formate:<\/strong> Buch, eBook<\/li>\n<li><strong>Buch-ISBN:<\/strong>\u200e\u200e 9783959675628<\/li>\n<\/ol>\n<div class=\"clearfix\"><\/div>\n<div class=\"buech-content-tipps buech-entity-placement\" id=\"buech-3141965415\"><div id=\"buech-2845772844\"><p>Oder gebraucht suchen bei <a href=\"https:\/\/www.awin1.com\/awclick.php?gid=362166&mid=11364&awinaffid=644643&linkid=2376078&clickref=\">Medimops<\/a>.<\/p><\/div><\/div><h2>Inhaltsangabe von &#8222;Der Gejagte&#8220;:<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.buecherserien.de\/de\/wp-content\/uploads\/gabriella-ullberg-westin-rokka-4.jpg\" alt=\"Der Gejagte von Gabriella Ullberg Westin\" width=\"250\" height=\"400\" \/>Der vierte Band um den ehemals kriminellen Kommissar Johan Rokka: Oktober in Hudiksvall, Nordschweden: Die Elchjagdsaison beginnt. Eine Gruppe von sechs J\u00e4gern bricht zur Jagd auf. Kurz darauf h\u00e4ngt im K\u00fchlhaus neben dem geh\u00e4uteten Elch eine aufgeschlitzte menschliche Leiche. Es handelt sich um einen der J\u00e4ger, eingeritzt in seine Haut ist die Ziffer 6. Johan Rokka beginnt zu ermitteln, doch auch er kann nicht verhindern, dass kurze Zeit sp\u00e4ter ein weiterer Kopf an einer Sennh\u00fctte h\u00e4ngt, daneben die Zahl 5. Die Verbindung zwischen den Verbrechen ist klar, doch wer macht Jagd auf die Sch\u00fctzen? Kann Rokka den T\u00e4ter stellen, bevor er auch die verbliebenen vier J\u00e4ger umbringt?<\/p>\n<div class=\"clearfix\"><\/div>\n<p id=\"buv_back_single\"><a href=\"https:\/\/www.buecherserien.de\/gabriella-ullberg-westin\/\">Zur\u00fcck zur Autorenseite<\/a><\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Der Kriminalroman &#8222;Der Gejagte&#8220; ist der 4. Band der Johan Rokka-Reihe von der schwedischen Autorin Gabriella Ullberg Westin. Titel bestellen bei: Amazon Thalia Hugendubel eBook.de Infos \u00fcber das Buch: Serie: Johan Rokka 4 Verlag: HarperCollins Seiten: 368 Ver\u00f6ffentlichung: 24.8.2021 Formate: Buch, eBook Buch-ISBN:\u200e\u200e 9783959675628 Inhaltsangabe von &#8222;Der Gejagte&#8220;: Der vierte Band um den ehemals kriminellen [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":24538,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[18],"tags":[435],"class_list":["post-24537","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-krimi-thriller","tag-gabriella-ullberg-westin"],"_links":{"self":[{"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/posts\/24537","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/comments?post=24537"}],"version-history":[{"count":0,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/posts\/24537\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/media\/24538"}],"wp:attachment":[{"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/media?parent=24537"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/categories?post=24537"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/tags?post=24537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}