{"id":24283,"date":"2022-09-24T10:34:22","date_gmt":"2022-09-24T08:34:22","guid":{"rendered":"https:\/\/www.buecherserien.de\/de\/?p=24283"},"modified":"2022-09-24T10:34:22","modified_gmt":"2022-09-24T08:34:22","slug":"karen-rose-des-todes-liebste-beute","status":"publish","type":"post","link":"https:\/\/www.buecherserien.de\/de\/karen-rose-des-todes-liebste-beute\/","title":{"rendered":"Karen Rose: Des Todes liebste Beute"},"content":{"rendered":"<div id=\"buv\">\n<p>Der Thriller &#8222;Des Todes liebste Beute&#8220; ist der 3. Band der Chicago-Reihe von der US-amerikanischen Autorin <a title=\"B\u00fccher von Karen Rose\" href=\"https:\/\/www.buecherserien.de\/karen-rose\/\">Karen Rose<\/a>.<\/p>\n<ul>\n<li>Titel bestellen bei:<\/li>\n<li class=\"buv_am\"><a title=\"Amazon.de\" href=\"https:\/\/www.amazon.de\/dp\/B005NGDN78\/ref=nosim?tag=buecherserien-21\">Amazon<\/a><\/li>\n<li class=\"buv_th\"><a title=\"Thalia.de\" href=\"https:\/\/www.awin1.com\/cread.php?awinmid=14158&amp;awinaffid=644643&amp;ued=https%3A%2F%2Fwww.thalia.de%2Fshop%2Fhome%2Fartikeldetails%2FEAN9783426413920\">Thalia<\/a><\/li>\n<li class=\"buv_hu\"><a title=\"Hugendubel.de\" href=\"https:\/\/clk.tradedoubler.com\/click?p=249407&#038;a=3222251&#038;url=https%3A%2F%2Fwww.hugendubel.de%2Fde%2Fproduct%3Fid%3D9783426413920\">Hugendubel<\/a><\/li>\n<li class=\"buv_eb\"><a title=\"eBook.de\" href=\"https:\/\/clk.tradedoubler.com\/click?p=324630&#038;a=3222251&#038;url=https%3A%2F%2Fwww.ebook.de%2Fde%2Fproduct%3Fid%3D9783426413920\">eBook.de<\/a><\/li>\n<\/ul>\n<ol>\n<li><strong>Infos \u00fcber das Buch:<\/strong><\/li>\n<li><strong>Serie:<\/strong> Chicago 3<\/li>\n<li><strong>Verlag:<\/strong> Knaur<\/li>\n<li><strong>Seiten:<\/strong> 608<\/li>\n<li><strong>Ver\u00f6ffentlichung:<\/strong> 1.8.2006<\/li>\n<li><strong>Formate:<\/strong> Buch, eBook, H\u00f6rbuch<\/li>\n<li><strong>Buch-ISBN:<\/strong> 9783426633373<\/li>\n<\/ol>\n<div class=\"clearfix\"><\/div>\n<div class=\"buech-content-tipps\" id=\"buech-1126003282\"><p>Oder gebraucht suchen bei <a href=\"https:\/\/www.awin1.com\/awclick.php?gid=362166&mid=11364&awinaffid=644643&linkid=2376078&clickref=\">Medimops<\/a>.<\/p><\/div><h2>Inhaltsangabe von &#8222;Des Todes liebste Beute&#8220;:<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.buecherserien.de\/de\/wp-content\/uploads\/karen-rose-chicago-3.jpg\" alt=\"Des Todes liebste Beute von Karen Rose\" width=\"250\" height=\"400\" \/>Ein Thriller, der unter die Haut geht Staatsanw\u00e4ltin Kristen Mayhew hat einen Verehrer. Er bezeichnet sich selbst als ihren ergebenen Diener \u2013 und schickt ihr regelm\u00e4\u00dfig Fotos seiner grausam zugerichteten Opfer. Es sind alles Verbrecher, gegen die Kristen vor Gericht keine Verurteilung durchsetzen konnte. Als der selbsternannte R\u00e4cher auch den Sohn eines Mafiapaten auf seine Todesliste setzt, ist Kristen in Gefahr. Denn nun hetzt die Mafia ihre Killer auf sie. Detective Abe Reagan schw\u00f6rt, die sch\u00f6ne Staatsanw\u00e4ltin zu sch\u00fctzen \u2026<\/p>\n<div class=\"clearfix\"><\/div>\n<p id=\"buv_back_single\"><a href=\"https:\/\/www.buecherserien.de\/karen-rose\/\">Zur\u00fcck zur Autorenseite<\/a><\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Der Thriller &#8222;Des Todes liebste Beute&#8220; ist der 3. Band der Chicago-Reihe von der US-amerikanischen Autorin Karen Rose. Titel bestellen bei: Amazon Thalia Hugendubel eBook.de Infos \u00fcber das Buch: Serie: Chicago 3 Verlag: Knaur Seiten: 608 Ver\u00f6ffentlichung: 1.8.2006 Formate: Buch, eBook, H\u00f6rbuch Buch-ISBN: 9783426633373 Inhaltsangabe von &#8222;Des Todes liebste Beute&#8220;: Ein Thriller, der unter die [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":24284,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[18],"tags":[408],"class_list":["post-24283","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-krimi-thriller","tag-karen-rose"],"_links":{"self":[{"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/posts\/24283","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/comments?post=24283"}],"version-history":[{"count":0,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/posts\/24283\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/media\/24284"}],"wp:attachment":[{"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/media?parent=24283"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/categories?post=24283"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/tags?post=24283"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}