{"id":24263,"date":"2022-09-24T10:25:50","date_gmt":"2022-09-24T08:25:50","guid":{"rendered":"https:\/\/www.buecherserien.de\/de\/?p=24263"},"modified":"2022-09-24T10:25:50","modified_gmt":"2022-09-24T08:25:50","slug":"karen-rose-feuer","status":"publish","type":"post","link":"https:\/\/www.buecherserien.de\/de\/karen-rose-feuer\/","title":{"rendered":"Karen Rose: Feuer"},"content":{"rendered":"<div id=\"buv\">\n<p>Der Thriller &#8222;Feuer&#8220; ist der 2. Band der Minneapolis-Reihe von der US-amerikanischen Autorin <a title=\"B\u00fccher von Karen Rose\" href=\"https:\/\/www.buecherserien.de\/karen-rose\/\">Karen Rose<\/a>.<\/p>\n<ul>\n<li>Titel bestellen bei:<\/li>\n<li class=\"buv_am\"><a title=\"Amazon.de\" href=\"https:\/\/www.amazon.de\/dp\/B005SZ0ZQG\/ref=nosim?tag=buecherserien-21\">Amazon<\/a><\/li>\n<li class=\"buv_th\"><a title=\"Thalia.de\" href=\"https:\/\/www.awin1.com\/cread.php?awinmid=14158&amp;awinaffid=644643&amp;ued=https%3A%2F%2Fwww.thalia.de%2Fshop%2Fhome%2Fartikeldetails%2FEAN9783426412763\">Thalia<\/a><\/li>\n<li class=\"buv_hu\"><a title=\"Hugendubel.de\" href=\"https:\/\/clk.tradedoubler.com\/click?p=249407&#038;a=3222251&#038;url=https%3A%2F%2Fwww.hugendubel.de%2Fde%2Fproduct%3Fid%3D9783426412763\">Hugendubel<\/a><\/li>\n<li class=\"buv_eb\"><a title=\"eBook.de\" href=\"https:\/\/clk.tradedoubler.com\/click?p=324630&#038;a=3222251&#038;url=https%3A%2F%2Fwww.ebook.de%2Fde%2Fproduct%3Fid%3D9783426412763\">eBook.de<\/a><\/li>\n<\/ul>\n<ol>\n<li><strong>Infos \u00fcber das Buch:<\/strong><\/li>\n<li><strong>Serie:<\/strong> Minneapolis 2<\/li>\n<li><strong>Verlag:<\/strong> Knaur<\/li>\n<li><strong>Seiten:<\/strong> 624<\/li>\n<li><strong>Ver\u00f6ffentlichung:<\/strong> 1.1.2010<\/li>\n<li><strong>Formate:<\/strong> Buch, eBook, H\u00f6rbuch<\/li>\n<li><strong>Buch-ISBN:<\/strong> 9783426503010<\/li>\n<\/ol>\n<div class=\"clearfix\"><\/div>\n<div class=\"buech-content-tipps\" id=\"buech-1967410620\"><p>Oder gebraucht suchen bei <a href=\"https:\/\/www.awin1.com\/awclick.php?gid=362166&mid=11364&awinaffid=644643&linkid=2376078&clickref=\">Medimops<\/a>.<\/p><\/div><h2>Inhaltsangabe von &#8222;Feuer&#8220;:<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.buecherserien.de\/de\/wp-content\/uploads\/karen-rose-minneapolis-2.jpg\" alt=\"Feuer von Karen Rose\" width=\"250\" height=\"400\" \/>Aus Leichtsinn verursachen vier College-Studenten einen Gro\u00dfbrand in einem Apartmentkomplex, bei dem ein junges M\u00e4dchen qualvoll verbrennt. Was sie nicht wissen: Sie werden beobachtet. Wenig sp\u00e4ter erhalten sie ein Video und die unmissverst\u00e4ndliche Anweisung, ein Warenhaus in Brand zu stecken. Sie haben keine Wahl und setzen ein Flammeninferno in Gang, das Feuerwehrmann Hunter und seine smarte Kollegin, Detective Olivia Sutherland, tagelang in Atem h\u00e4lt. Dann stirbt der erste der Freunde \u2013 bei einem Autounfall, angeblich. Als wenig sp\u00e4ter der n\u00e4chste ums Leben kommt, entsteht Panik. Was f\u00fcr ein grausames Spiel spielt dieser Erpresser? Er muss zum Schweigen gebracht werden \u2013 f\u00fcr immer\u2026<\/p>\n<div class=\"clearfix\"><\/div>\n<p id=\"buv_back_single\"><a href=\"https:\/\/www.buecherserien.de\/karen-rose\/\">Zur\u00fcck zur Autorenseite<\/a><\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Der Thriller &#8222;Feuer&#8220; ist der 2. Band der Minneapolis-Reihe von der US-amerikanischen Autorin Karen Rose. Titel bestellen bei: Amazon Thalia Hugendubel eBook.de Infos \u00fcber das Buch: Serie: Minneapolis 2 Verlag: Knaur Seiten: 624 Ver\u00f6ffentlichung: 1.1.2010 Formate: Buch, eBook, H\u00f6rbuch Buch-ISBN: 9783426503010 Inhaltsangabe von &#8222;Feuer&#8220;: Aus Leichtsinn verursachen vier College-Studenten einen Gro\u00dfbrand in einem Apartmentkomplex, bei [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":24264,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[18],"tags":[408],"class_list":["post-24263","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-krimi-thriller","tag-karen-rose"],"_links":{"self":[{"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/posts\/24263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/comments?post=24263"}],"version-history":[{"count":0,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/posts\/24263\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/media\/24264"}],"wp:attachment":[{"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/media?parent=24263"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/categories?post=24263"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/tags?post=24263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}