{"id":15340,"date":"2021-12-27T10:29:10","date_gmt":"2021-12-27T09:29:10","guid":{"rendered":"https:\/\/www.buecherserien.de\/de\/?p=15340"},"modified":"2023-09-24T12:20:42","modified_gmt":"2023-09-24T10:20:42","slug":"michael-connelly-kein-engel-so-rein","status":"publish","type":"post","link":"https:\/\/www.buecherserien.de\/de\/michael-connelly-kein-engel-so-rein\/","title":{"rendered":"Michael Connelly: Kein Engel so rein"},"content":{"rendered":"<div id=\"buv\">\n<p>Der Kriminalroman &#8222;Kein Engel so rein&#8220; ist der 8. Band der Harry Bosch-Reihe von dem US-amerikanischen Autor <a title=\"B\u00fccher von Michael Connelly\" href=\"https:\/\/www.buecherserien.de\/michael-connelly\/\">Michael Connelly<\/a>.<\/p>\n<ul>\n<li>Titel bestellen bei:<\/li>\n<li class=\"buv_am\"><a title=\"Amazon.de\" href=\"https:\/\/www.amazon.de\/dp\/B0C4LXZFTL\/ref=nosim?tag=buecherserien-21\">Amazon<\/a><\/li>\n<li class=\"buv_th\"><a title=\"Thalia.de\" href=\"https:\/\/www.awin1.com\/cread.php?awinmid=14158&amp;awinaffid=644643&amp;ued=https%3A%2F%2Fwww.thalia.de%2Fshop%2Fhome%2Fartikeldetails%2FEAN9783311704485\">Thalia<\/a><\/li>\n<li class=\"buv_hu\"><a title=\"Hugendubel.de\" href=\"https:\/\/clk.tradedoubler.com\/click?p=249407&#038;a=3222251&#038;url=https%3A%2F%2Fwww.hugendubel.de%2Fde%2Fproduct%3Fid%3D9783311704485\">Hugendubel<\/a><\/li>\n<li class=\"buv_eb\"><a title=\"eBook.de\" href=\"https:\/\/clk.tradedoubler.com\/click?p=324630&#038;a=3222251&#038;url=https%3A%2F%2Fwww.ebook.de%2Fde%2Fproduct%3Fid%3D9783311704485\">eBook.de<\/a><\/li>\n<\/ul>\n<ol>\n<li><strong>Infos \u00fcber das Buch:<\/strong><\/li>\n<li><strong>Serie:<\/strong> Harry Bosch 8<\/li>\n<li><strong>Verlag:<\/strong> Heyne<\/li>\n<li><strong>Seiten:<\/strong> 506<\/li>\n<li><strong>Ver\u00f6ffentlichung:<\/strong> 12.8.2003<\/li>\n<li><strong>Formate:<\/strong> Buch, eBook<\/li>\n<li><strong>Buch-ISBN:<\/strong>\u200e\u200e 9783311155195<\/li>\n<\/ol>\n<div class=\"clearfix\"><\/div>\n<div class=\"buech-content-tipps\" id=\"buech-531887073\"><p>Oder gebraucht suchen bei <a href=\"https:\/\/www.awin1.com\/awclick.php?gid=362166&mid=11364&awinaffid=644643&linkid=2376078&clickref=\">Medimops<\/a>.<\/p><\/div><h2>Inhaltsangabe von &#8222;Kein Engel so rein&#8220;:<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.buecherserien.de\/de\/wp-content\/uploads\/michael-connelly-harry-bosch-8.webp\" alt=\"Kein Engel so rein von Michael Connelly\" width=\"250\" height=\"400\" \/>Am Neujahrstag erh\u00e4lt Bosch in seinem Dienstwagen die Nachricht, dass in den Bergen nahe Hollywoods ein Hund im Wald einen Knochen ausgegraben hat. Ein Arzt hat den Fund als Teil eines menschlichen Skeletts identifiziert. Bosch findet im Wald unter dem Laub verstreut ein paar weitere Knochen. In der Gerichtsmedizin stellt sich heraus, dass sie die Reste des Skeletts eines etwa zehnj\u00e4hrigen Jungen sind. Ganz offensichtlich wurde das Kind ermordet. Harry Bosch l\u00e4sst der Fall nicht los, obwohl der Mord mehr als zwanzig Jahre zur\u00fcckliegt. Das Schicksal dieses Jungen erinnert ihn zu sehr an seine eigene, elternlose Kindheit. Je tiefer er in die Vergangenheit des Jungen eintaucht, desto mehr erf\u00e4hrt er \u00fcber sich selbst und den Grund, warum das Kind von zu Hause weggelaufen war.<\/p>\n<div class=\"clearfix\"><\/div>\n<p id=\"buv_back_single\"><a href=\"https:\/\/www.buecherserien.de\/michael-connelly\/\">Zur\u00fcck zur Serie<\/a><\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Der Kriminalroman &#8222;Kein Engel so rein&#8220; ist der 8. Band der Harry Bosch-Reihe von dem US-amerikanischen Autor Michael Connelly. Titel bestellen bei: Amazon Thalia Hugendubel eBook.de Infos \u00fcber das Buch: Serie: Harry Bosch 8 Verlag: Heyne Seiten: 506 Ver\u00f6ffentlichung: 12.8.2003 Formate: Buch, eBook Buch-ISBN:\u200e\u200e 9783311155195 Inhaltsangabe von &#8222;Kein Engel so rein&#8220;: Am Neujahrstag erh\u00e4lt Bosch [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":27851,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[18],"tags":[330],"class_list":["post-15340","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-krimi-thriller","tag-michael-connelly"],"_links":{"self":[{"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/posts\/15340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/comments?post=15340"}],"version-history":[{"count":0,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/posts\/15340\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/media\/27851"}],"wp:attachment":[{"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/media?parent=15340"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/categories?post=15340"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/tags?post=15340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}