{"id":13725,"date":"2021-11-14T10:59:00","date_gmt":"2021-11-14T09:59:00","guid":{"rendered":"https:\/\/www.buecherserien.de\/de\/?p=13725"},"modified":"2021-11-14T10:59:00","modified_gmt":"2021-11-14T09:59:00","slug":"faye-kellerman-der-wird-euch-mit-feuer-taufen","status":"publish","type":"post","link":"https:\/\/www.buecherserien.de\/de\/faye-kellerman-der-wird-euch-mit-feuer-taufen\/","title":{"rendered":"Faye Kellerman: Der wird Euch mit Feuer taufen"},"content":{"rendered":"<div id=\"buv\">\n<p>Der Kriminalroman &#8222;Der wird Euch mit Feuer taufen&#8220; ist der 11. Band der Rina Lazarus &#038; Peter Decker-Reihe von der US-amerikanischen Autorin <a title=\"B\u00fccher von Faye Kellerman\" href=\"https:\/\/www.buecherserien.de\/faye-kellerman\/\">Faye Kellerman<\/a>.<\/p>\n<ul>\n<li>Titel bestellen bei:<\/li>\n<li class=\"buv_am\"><a title=\"Amazon.de\" href=\"https:\/\/www.amazon.de\/dp\/3442726735\/ref=nosim?tag=buecherserien-21\">Amazon<\/a><\/li>\n<\/ul>\n<ol>\n<li><strong>Infos \u00fcber das Buch:<\/strong><\/li>\n<li><strong>Serie:<\/strong> Lazarus &#038; Decker 11<\/li>\n<li><strong>Verlag:<\/strong>\u200e btb<\/li>\n<li><strong>Seiten:<\/strong> 448<\/li>\n<li><strong>Ver\u00f6ffentlichung:<\/strong> 1.9.2002<\/li>\n<li><strong>Formate:<\/strong> Buch<\/li>\n<li><strong>Buch-ISBN:<\/strong>\u200e\u200e 9783442726738<\/li>\n<\/ol>\n<div class=\"clearfix\"><\/div>\n<div class=\"buech-content-tipps\" id=\"buech-2663883642\"><p>Oder gebraucht suchen bei <a href=\"https:\/\/www.awin1.com\/awclick.php?gid=362166&mid=11364&awinaffid=644643&linkid=2376078&clickref=\">Medimops<\/a>.<\/p><\/div><h2>Inhaltsangabe von &#8222;Der wird Euch mit Feuer taufen&#8220;:<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.buecherserien.de\/de\/wp-content\/uploads\/faye-kellerman-lazarus-decker-11.jpg\" alt=\"Der wird Euch mit Feuer taufen von Faye Kellerman\" width=\"250\" height=\"400\" \/>Als Peter Decker, Lieutnant bei der Polizei von Los Angeles, zu dem toten Sektenf\u00fchrer Jupiter gerufen wird, empfangen ihn die Mitglieder der Gruppe &#8222;Orden der Ringe Gottes&#8220; mit offener Feindseligkeit. Zun\u00e4chst ist nicht erkennbar, ob der ehemals ber\u00fchmte Physiker Emil Euler ermordet wurde oder ob er sich selbst t\u00f6tete. Peter Decker sp\u00fcrt jedoch schnell, dass es hinter der Fassade aus bedingungsloser Loyalit\u00e4t in der Gemeinschaft rumort. Machtk\u00e4mpfe um den F\u00fchrungsanspruch und viel Geld vergiften die Atmosph\u00e4re. Dann verschwinden zwei Sektenmitglieder und ein weiteres wird ermordet. Decker steht vor einem R\u00e4tsel &#8211; bis ihm die Tochter des Sektenf\u00fchrers, die Physikerin Europa, begegnet, und ihm einiges klar wird&#8230;<\/p>\n<div class=\"clearfix\"><\/div>\n<p id=\"buv_back_single\"><a href=\"https:\/\/www.buecherserien.de\/faye-kellerman\/\">Zur\u00fcck zur Autorenseite<\/a><\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Der Kriminalroman &#8222;Der wird Euch mit Feuer taufen&#8220; ist der 11. Band der Rina Lazarus &#038; Peter Decker-Reihe von der US-amerikanischen Autorin Faye Kellerman. Titel bestellen bei: Amazon Infos \u00fcber das Buch: Serie: Lazarus &#038; Decker 11 Verlag:\u200e btb Seiten: 448 Ver\u00f6ffentlichung: 1.9.2002 Formate: Buch Buch-ISBN:\u200e\u200e 9783442726738 Inhaltsangabe von &#8222;Der wird Euch mit Feuer taufen&#8220;: [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":13726,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[18],"tags":[198],"class_list":["post-13725","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-krimi-thriller","tag-faye-kellerman"],"_links":{"self":[{"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/posts\/13725","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/comments?post=13725"}],"version-history":[{"count":0,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/posts\/13725\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/media\/13726"}],"wp:attachment":[{"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/media?parent=13725"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/categories?post=13725"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/tags?post=13725"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}