{"id":11922,"date":"2021-10-05T15:53:00","date_gmt":"2021-10-05T13:53:00","guid":{"rendered":"https:\/\/www.buecherserien.de\/de\/?p=11922"},"modified":"2021-10-05T15:53:00","modified_gmt":"2021-10-05T13:53:00","slug":"nele-neuhaus-im-wald","status":"publish","type":"post","link":"https:\/\/www.buecherserien.de\/de\/nele-neuhaus-im-wald\/","title":{"rendered":"Nele Neuhaus: Im Wald"},"content":{"rendered":"<div id=\"buv\">\n<p>Der Kriminalroman &#8222;Im Wald&#8220; ist der 8. Band der Bodenstein &#038; Sander-Reihe von der deutschen Autorin <a title=\"B\u00fccher von Nele Neuhaus\" href=\"https:\/\/www.buecherserien.de\/nele-neuhaus\/\">Nele Neuhaus<\/a>.<\/p>\n<ul>\n<li>Titel bestellen bei:<\/li>\n<li class=\"buv_am\"><a title=\"Amazon.de\" href=\"https:\/\/www.amazon.de\/dp\/B01F8NXH44\/ref=nosim?tag=buecherserien-21\">Amazon<\/a><\/li>\n<li class=\"buv_th\"><a title=\"Thalia.de\" href=\"https:\/\/www.awin1.com\/cread.php?awinmid=14158&amp;awinaffid=644643&amp;ued=https%3A%2F%2Fwww.thalia.de%2Fshop%2Fhome%2Fartikeldetails%2FEAN9783843714297\">Thalia<\/a><\/li>\n<li class=\"buv_hu\"><a title=\"Hugendubel.de\" href=\"https:\/\/clk.tradedoubler.com\/click?p=249407&#038;a=3222251&#038;url=https%3A%2F%2Fwww.hugendubel.de%2Fde%2Fproduct%3Fid%3D9783843714297\">Hugendubel<\/a><\/li>\n<li class=\"buv_eb\"><a title=\"eBook.de\" href=\"https:\/\/clk.tradedoubler.com\/click?p=324630&#038;a=3222251&#038;url=https%3A%2F%2Fwww.ebook.de%2Fde%2Fproduct%3Fid%3D9783843714297\">eBook.de<\/a><\/li>\n<\/ul>\n<ol>\n<li><strong>Infos \u00fcber das Buch:<\/strong><\/li>\n<li><strong>Serie:<\/strong> Bodenstein &#038; Sander 8<\/li>\n<li><strong>Verlag:<\/strong> Ullstein<\/li>\n<li><strong>Seiten:<\/strong> 560<\/li>\n<li><strong>Ver\u00f6ffentlichung:<\/strong> 14.10.2016<\/li>\n<li><strong>Formate:<\/strong> Buch, eBook, H\u00f6rbuch<\/li>\n<li><strong>Buch-ISBN:<\/strong>\u200e\u200e 9783548289793<\/li>\n<\/ol>\n<div class=\"clearfix\"><\/div>\n<div class=\"buech-content-tipps\" id=\"buech-1496605309\"><p>Oder gebraucht suchen bei <a href=\"https:\/\/www.awin1.com\/awclick.php?gid=362166&mid=11364&awinaffid=644643&linkid=2376078&clickref=\">Medimops<\/a>.<\/p><\/div><h2>Inhaltsangabe von &#8222;Im Wald&#8220;:<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.buecherserien.de\/de\/wp-content\/uploads\/nele-neuhaus-bodenstein-sander-8.jpg\" alt=\"Im Wald von Nele Neuhaus\" width=\"250\" height=\"400\" \/>Mitten in der Nacht geht im Wald bei Ruppertshain ein Wohnwagen in Flammen auf. Aus den Tr\u00fcmmern wird eine Leiche geborgen.<br \/>\nOliver von Bodenstein und Pia Sander vom K11 in Hofheim ermitteln zun\u00e4chst wegen Brandstiftung, doch bald auch wegen Mordes.<br \/>\nKurz darauf wird eine todkranke alte Frau in einem Hospiz ermordet. Bodenstein ist ersch\u00fcttert, er kannte die Frau seit seiner Kindheit.<br \/>\nDie Ermittlungen f\u00fchren Pia und ihn vierzig Jahre in die Vergangenheit, in den Sommer 1972, als Bodensteins bester Freund Artur spurlos verschwand.<br \/>\nEin Kindheitstrauma, das er nie \u00fcberwand &#8211; und f\u00fcr viele Ruppertshainer eine alte Geschichte, an die man besser nicht r\u00fchrt.<br \/>\nEs bleibt nicht bei zwei Toten. Liegt ein Fluch \u00fcber dem Dorf? <\/p>\n<div class=\"clearfix\"><\/div>\n<p id=\"buv_back_single\"><a href=\"https:\/\/www.buecherserien.de\/nele-neuhaus\/\">Zur\u00fcck zur Autorenseite<\/a><\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Der Kriminalroman &#8222;Im Wald&#8220; ist der 8. Band der Bodenstein &#038; Sander-Reihe von der deutschen Autorin Nele Neuhaus. Titel bestellen bei: Amazon Thalia Hugendubel eBook.de Infos \u00fcber das Buch: Serie: Bodenstein &#038; Sander 8 Verlag: Ullstein Seiten: 560 Ver\u00f6ffentlichung: 14.10.2016 Formate: Buch, eBook, H\u00f6rbuch Buch-ISBN:\u200e\u200e 9783548289793 Inhaltsangabe von &#8222;Im Wald&#8220;: Mitten in der Nacht geht [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":11925,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[18],"tags":[173],"class_list":["post-11922","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-krimi-thriller","tag-nele-neuhaus"],"_links":{"self":[{"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/posts\/11922","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/comments?post=11922"}],"version-history":[{"count":0,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/posts\/11922\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/media\/11925"}],"wp:attachment":[{"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/media?parent=11922"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/categories?post=11922"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.buecherserien.de\/de\/wp-json\/wp\/v2\/tags?post=11922"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}